{"id":14302,"date":"2017-08-11T11:43:15","date_gmt":"2017-08-11T09:43:15","guid":{"rendered":"https:\/\/www.radioking.com\/blog\/?p=14302"},"modified":"2025-11-28T14:21:03","modified_gmt":"2025-11-28T13:21:03","slug":"comment-gagner-de-largent-grace-a-sa-radio","status":"publish","type":"post","link":"https:\/\/fr.radioking.com\/blog\/comment-gagner-de-largent-grace-a-sa-radio\/","title":{"rendered":"Comment gagner de l&rsquo;argent gr\u00e2ce \u00e0 sa radio ?"},"content":{"rendered":"\n<p>Il existe diff\u00e9rents moyens de mon\u00e9tiser son projet radio. <\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Vous pouvez partir \u00e0 la recherche d&rsquo;une r\u00e9gie publicitaire, cr\u00e9er des partenariats avec des festivals ou des collectivit\u00e9s locales ou encore lancer votre boutique en ligne pour vendre des objets collector !<\/p>\n\n\n\n<p><strong>Ces id\u00e9es vous permettront de r\u00e9aliser plus ou moins rapidement des b\u00e9n\u00e9fices tout en faisant d\u00e9coller votre radio<\/strong>, les deux allant g\u00e9n\u00e9ralement de pair !<\/p>\n\n\n\n<p>D\u00e9couvrez notre vid\u00e9o \u00e0 ce sujet :<\/p>\n\n\n\n<p><iframe loading=\"lazy\" data-src=\"https:\/\/www.youtube.com\/embed\/CJwHDTAzMS4\" width=\"560\" height=\"315\" frameborder=\"0\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n\n\n\n<p><strong>Note \u00e0 l&rsquo;intention de nos lecteurs : <\/strong>Ces id\u00e9es ne vous rendront pas riches en un jour (h\u00e9las !). N\u00e9anmoins, nous vous donnons ici, quelques pistes faciles \u00e0 mettre en place pour gagner de l&rsquo;argent avec votre radio en ligne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #efbc12;\"><strong>R\u00e9alisez des partenariats strat\u00e9giques<\/strong><\/span><\/h3>\n\n\n\n<p>Lorsque vous d\u00e9butez un projet, les r\u00e9gies publicitaires peuvent parfois se montrer r\u00e9ticentes \u00e0 investir imm\u00e9diatement. Cependant, il existe&nbsp;un moyen un peu plus simple d&rsquo;obtenir des financements avec votre station de radio.<strong> R\u00e9aliser des partenariats !<\/strong> Vos animateurs pourraient placer quelques mots sur votre sponsor avant une \u00e9mission par exemple. Si vous \u00eates une radio r\u00e9gionale, il peut \u00eatre int\u00e9ressant de proposer aux collectivit\u00e9s locales de gagner de la visibilit\u00e9 contre r\u00e9mun\u00e9rations ! <strong>Le plus important est de s&rsquo;entourer de partenaires<\/strong> avec qui vous vous sentez \u00e0 l&rsquo;aise et <strong>qui refl\u00e8tent votre identit\u00e9, mais surtout qui correspondent \u00e0 vos auditeurs.<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/fr.radioking.com\/p\/livre-blanc-monetiser-gagner-argent-webradio\/\"><img decoding=\"async\" loading=\"lazy\" width=\"2428\" height=\"990\" data-src=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent.jpg\" alt=\"\" class=\"wp-image-21808 lazyload\" data-srcset=\"https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent.jpg?lossy=0&amp;strip=1&amp;webp=1 2428w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-300x122.jpg?lossy=0&amp;strip=1&amp;webp=1 300w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-640x261.jpg?lossy=0&amp;strip=1&amp;webp=1 640w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-768x313.jpg?lossy=0&amp;strip=1&amp;webp=1 768w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-1536x626.jpg?lossy=0&amp;strip=1&amp;webp=1 1536w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-2048x835.jpg?lossy=0&amp;strip=1&amp;webp=1 2048w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-1920x783.jpg?lossy=0&amp;strip=1&amp;webp=1 1920w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-1680x685.jpg?lossy=0&amp;strip=1&amp;webp=1 1680w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-1240x506.jpg?lossy=0&amp;strip=1&amp;webp=1 1240w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-860x351.jpg?lossy=0&amp;strip=1&amp;webp=1 860w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-680x277.jpg?lossy=0&amp;strip=1&amp;webp=1 680w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-500x204.jpg?lossy=0&amp;strip=1&amp;webp=1 500w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-400x163.jpg?lossy=0&amp;strip=1&amp;webp=1 400w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-200x82.jpg?lossy=0&amp;strip=1&amp;webp=1 200w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-50x20.jpg?lossy=0&amp;strip=1&amp;webp=1 50w\" data-sizes=\"(max-width: 2428px) 100vw, 2428px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 2428px; --smush-placeholder-aspect-ratio: 2428\/990;\" \/><noscript><img decoding=\"async\" loading=\"lazy\" width=\"2428\" height=\"990\" src=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent.jpg\" alt=\"\" class=\"wp-image-21808\" srcset=\"https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent.jpg?lossy=0&amp;strip=1&amp;webp=1 2428w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-300x122.jpg?lossy=0&amp;strip=1&amp;webp=1 300w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-640x261.jpg?lossy=0&amp;strip=1&amp;webp=1 640w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-768x313.jpg?lossy=0&amp;strip=1&amp;webp=1 768w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-1536x626.jpg?lossy=0&amp;strip=1&amp;webp=1 1536w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-2048x835.jpg?lossy=0&amp;strip=1&amp;webp=1 2048w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-1920x783.jpg?lossy=0&amp;strip=1&amp;webp=1 1920w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-1680x685.jpg?lossy=0&amp;strip=1&amp;webp=1 1680w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-1240x506.jpg?lossy=0&amp;strip=1&amp;webp=1 1240w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-860x351.jpg?lossy=0&amp;strip=1&amp;webp=1 860w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-680x277.jpg?lossy=0&amp;strip=1&amp;webp=1 680w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-500x204.jpg?lossy=0&amp;strip=1&amp;webp=1 500w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-400x163.jpg?lossy=0&amp;strip=1&amp;webp=1 400w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-200x82.jpg?lossy=0&amp;strip=1&amp;webp=1 200w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Argent-50x20.jpg?lossy=0&amp;strip=1&amp;webp=1 50w\" sizes=\"(max-width: 2428px) 100vw, 2428px\" \/><\/noscript><\/a><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #efbc12;\"><strong>Ins\u00e9rez de la publicit\u00e9 \u00e0 l&rsquo;antenne&nbsp;<\/strong><\/span><\/h3>\n\n\n\n<p>Vendre son temps d&rsquo;antenne est une tr\u00e8s bonne fa\u00e7on d&rsquo;obtenir des revenus. Cependant, gardez \u00e0 l&rsquo;esprit que<strong> les investisseurs voudront, avant tout, en savoir plus sur votre audience.<\/strong> En effet, ils doivent \u00eatre assur\u00e9s que votre radio repr\u00e9sente un atout pour eux.<\/p>\n\n\n\n<p>Nous vous recommandons donc d&rsquo;<strong>\u00e9tudier votre audience<\/strong>. Quel type d&rsquo;auditeur attirez-vous ? Son \u00e2ge, son lieu de r\u00e9sidence, ses go\u00fbts musicaux, etc. Une station de radio Pop Hits attire, dans la majorit\u00e9 des cas, un public l\u00e9g\u00e8rement plus jeune qu&rsquo;une station de radio classique. Si vous ne connaissez pas encore votre audience, n&rsquo;h\u00e9sitez pas \u00e0 l&rsquo;\u00e9tudier dans la rubrique <a href=\"https:\/\/manager.radioking.com\/radio\/0\/statistics\/live\">Statistiques<\/a>&nbsp;de votre Manager Radio.<\/p>\n\n\n\n<p><strong>Planifier des publicit\u00e9s ou des jingles entre vos programmes c&rsquo;est bien, mais int\u00e9resser vos auditeurs c&rsquo;est mieux !<\/strong>&nbsp;La derni\u00e8re chose que vous souhaitez, c&rsquo;est que vos auditeurs changent de station, d&rsquo;o\u00f9 l&rsquo;importance des publicit\u00e9s cibl\u00e9es.&nbsp;<span style=\"font-size: 1rem;\"><strong>Trouver le bon annonceur est le moyen le plus efficace de g\u00e9n\u00e9rer des revenus sans heurter ses auditeurs.<\/strong><\/span><\/p>\n\n\n\n<p><strong>Astuce :<\/strong>&nbsp; Avec le <a href=\"https:\/\/manager.radioking.com\/radio\/dashboard\">Manager Radio<\/a>, t\u00e9l\u00e9chargez directement vos publicit\u00e9s dans le bac <em>Publicit\u00e9s<\/em> afin d&rsquo;\u00e9viter que celles-ci ne soient utilis\u00e9es par le <strong>Comblage<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #efbc12;\"><b>Rejoignez<\/b><strong>&nbsp;un programme d&rsquo;affiliation<\/strong><\/span><\/h3>\n\n\n\n<p>En quelques clics vous pouvez mon\u00e9tiser votre radio facilement gr\u00e2ce aux programmes d&rsquo;affiliation. Par exemple, <strong>le programme d&rsquo;affiliation d&rsquo;Apple vous propose de gagner 7% de commission<\/strong> \u00e0 chaque fois qu&rsquo;une personne ach\u00e8te un titre via votre <a href=\"https:\/\/fr.radioking.com\/tarifs-player\">Player Radio<\/a>. Si vous poss\u00e9dez d\u00e9j\u00e0 un compte assurez-vous qu&rsquo;il soit bien configur\u00e9 gr\u00e2ce \u00e0 ce tutoriel :&nbsp;<a href=\"https:\/\/www.radioking.com\/on\/knowledgebase\/136\/Configure-iTunes-monetization.html\">comment configurer la mon\u00e9tisation iTunes<\/a>&nbsp;sur votre Manager Radio.<\/p>\n\n\n<div class='eckosc eckosc_full_width_block'><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-14284 size-full lazyload\" data-src=\"https:\/\/fr.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise.jpg\" alt=\"\" width=\"1280\" height=\"628\" data-srcset=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise.jpg 1280w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-300x147.jpg 300w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-768x377.jpg 768w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-640x314.jpg 640w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-1240x608.jpg 1240w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-860x422.jpg 860w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-680x334.jpg 680w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-500x245.jpg 500w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-400x196.jpg 400w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-200x98.jpg 200w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-50x25.jpg 50w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/628;\" \/><noscript><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-14284 size-full\" src=\"https:\/\/fr.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise.jpg\" alt=\"\" width=\"1280\" height=\"628\" srcset=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise.jpg 1280w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-300x147.jpg 300w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-768x377.jpg 768w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-640x314.jpg 640w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-1240x608.jpg 1240w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-860x422.jpg 860w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-680x334.jpg 680w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-500x245.jpg 500w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-400x196.jpg 400w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-200x98.jpg 200w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/merchandise-50x25.jpg 50w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/noscript><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #efbc12;\"><b>Cr\u00e9ez une boutique en ligne<\/b><\/span><\/h3>\n\n\n\n<p>Qui n&rsquo;aime pas les produits d\u00e9riv\u00e9s ? <strong>Cr\u00e9er sa boutique en ligne est un excellent moyen de gagner de l&rsquo;argent tout en augmentant votre visibilit\u00e9. <\/strong>Lancez un tee-shirt avec le logo de votre radio ou la phrase f\u00e9tiche d&rsquo;un de vos animateurs ! En plus de<strong> r\u00e9aliser des b\u00e9n\u00e9fices<\/strong>, votre radio deviendra une marque !<\/p>\n\n\n\n<p>N&rsquo;oubliez pas d&rsquo;ajouter des&nbsp;stickers \u00e0 votre boutique, en plus d&rsquo;\u00eatre peu co\u00fbteux pour vos auditeurs ils sont un excellent moyen de se faire conna\u00eetre et de marquer les esprits, une publicit\u00e9 \u00e0 bas co\u00fbt qui peut vous rapporter gros.<\/p>\n\n\n\n<p><strong>Astuce <\/strong>: Il existe des tas de plateformes pour vous aider \u00e0 cr\u00e9er votre propre boutique en ligne. Par exemple, jetez un oeil du c\u00f4t\u00e9 de&nbsp;<strong><a href=\"https:\/\/www.spreadshirt.com\" target=\"_blank\" rel=\"noopener\">Spreadshirt<\/a><\/strong>,&nbsp;<strong><a href=\"http:\/\/www.awesomemerchandise.com\/\" target=\"_blank\" rel=\"noopener\">Awesome Merchandise<\/a><\/strong> ou bien&nbsp;<strong><a href=\"https:\/\/www.printful.com\/\" target=\"_blank\" rel=\"noopener\">Printful<\/a><\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/fr.radioking.com\/p\/livre-blanc-monetiser-gagner-argent-webradio\/\"><img decoding=\"async\" loading=\"lazy\" width=\"2428\" height=\"990\" data-src=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation.jpg\" alt=\"\" class=\"wp-image-21810 lazyload\" data-srcset=\"https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation.jpg?lossy=0&amp;strip=1&amp;webp=1 2428w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-300x122.jpg?lossy=0&amp;strip=1&amp;webp=1 300w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-640x261.jpg?lossy=0&amp;strip=1&amp;webp=1 640w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-768x313.jpg?lossy=0&amp;strip=1&amp;webp=1 768w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-1536x626.jpg?lossy=0&amp;strip=1&amp;webp=1 1536w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-2048x835.jpg?lossy=0&amp;strip=1&amp;webp=1 2048w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-1920x783.jpg?lossy=0&amp;strip=1&amp;webp=1 1920w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-1680x685.jpg?lossy=0&amp;strip=1&amp;webp=1 1680w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-1240x506.jpg?lossy=0&amp;strip=1&amp;webp=1 1240w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-860x351.jpg?lossy=0&amp;strip=1&amp;webp=1 860w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-680x277.jpg?lossy=0&amp;strip=1&amp;webp=1 680w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-500x204.jpg?lossy=0&amp;strip=1&amp;webp=1 500w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-400x163.jpg?lossy=0&amp;strip=1&amp;webp=1 400w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-200x82.jpg?lossy=0&amp;strip=1&amp;webp=1 200w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-50x20.jpg?lossy=0&amp;strip=1&amp;webp=1 50w\" data-sizes=\"(max-width: 2428px) 100vw, 2428px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 2428px; --smush-placeholder-aspect-ratio: 2428\/990;\" \/><noscript><img decoding=\"async\" loading=\"lazy\" width=\"2428\" height=\"990\" src=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation.jpg\" alt=\"\" class=\"wp-image-21810\" srcset=\"https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation.jpg?lossy=0&amp;strip=1&amp;webp=1 2428w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-300x122.jpg?lossy=0&amp;strip=1&amp;webp=1 300w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-640x261.jpg?lossy=0&amp;strip=1&amp;webp=1 640w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-768x313.jpg?lossy=0&amp;strip=1&amp;webp=1 768w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-1536x626.jpg?lossy=0&amp;strip=1&amp;webp=1 1536w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-2048x835.jpg?lossy=0&amp;strip=1&amp;webp=1 2048w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-1920x783.jpg?lossy=0&amp;strip=1&amp;webp=1 1920w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-1680x685.jpg?lossy=0&amp;strip=1&amp;webp=1 1680w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-1240x506.jpg?lossy=0&amp;strip=1&amp;webp=1 1240w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-860x351.jpg?lossy=0&amp;strip=1&amp;webp=1 860w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-680x277.jpg?lossy=0&amp;strip=1&amp;webp=1 680w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-500x204.jpg?lossy=0&amp;strip=1&amp;webp=1 500w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-400x163.jpg?lossy=0&amp;strip=1&amp;webp=1 400w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-200x82.jpg?lossy=0&amp;strip=1&amp;webp=1 200w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2017\/08\/PSD-CTA-FR-Monetisation-50x20.jpg?lossy=0&amp;strip=1&amp;webp=1 50w\" sizes=\"(max-width: 2428px) 100vw, 2428px\" \/><\/noscript><\/a><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #efbc12;\"><strong>Dons et Financement Participatif<\/strong><\/span><\/h3>\n\n\n<div class='eckosc eckosc_full_width_block'>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-14272 size-full lazyload\" data-src=\"https:\/\/fr.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar.png\" alt=\"\" width=\"1280\" height=\"628\" data-srcset=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar.png 1280w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-300x147.png 300w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-768x377.png 768w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-640x314.png 640w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-1240x608.png 1240w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-860x422.png 860w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-680x334.png 680w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-500x245.png 500w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-400x196.png 400w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-200x98.png 200w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-50x25.png 50w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/628;\" \/><noscript><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-14272 size-full\" src=\"https:\/\/fr.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar.png\" alt=\"\" width=\"1280\" height=\"628\" srcset=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar.png 1280w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-300x147.png 300w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-768x377.png 768w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-640x314.png 640w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-1240x608.png 1240w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-860x422.png 860w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-680x334.png 680w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-500x245.png 500w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-400x196.png 400w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-200x98.png 200w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/cat-guitar-50x25.png 50w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/noscript><\/div>\n\n\n\n<p>Croyez-le ou non, il existe des tas de personnes g\u00e9n\u00e9reuses autour de vous alors ne passez pas \u00e0 c\u00f4t\u00e9 de cette opportunit\u00e9 ! <strong>Cr\u00e9ez vous-m\u00eame un bouton d&rsquo;appel aux dons<\/strong> en utilisant une plateforme telle que\u00a0<strong>PayPal<\/strong>\u00a0ou r\u00e9alisez un financement participatif sur Tipeee. Vous pourrez facilement les int\u00e9grer sur votre Site Radio. <strong>Vous pouvez \u00e9galement retrouver toutes nos astuces sur notre article d\u00e9di\u00e9 au financement participatif. \u00a0<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading has-luminous-vivid-amber-color has-text-color\">KissKissBankBank, la solution pour financer votre webradio gr\u00e2ce \u00e0 votre communaut\u00e9<\/h3>\n\n\n\n<p>Lancez-vous sur KissKissBankBank, la plateforme fran\u00e7aise de financement participatif avec le meilleur accompagnement pour la cr\u00e9ation ind\u00e9pendante ! Vous pouvez financer votre projet soit par une cagnotte (sur une p\u00e9riode d\u00e9finie) soit sur le temps long, gr\u00e2ce \u00e0&nbsp;<strong><a href=\"https:\/\/abonnement.kisskissbankbank.com\/\">l&rsquo;abonnement<\/a><\/strong>. Vos auditeurs peuvent soutenir votre radio avec des dons r\u00e9currents de fa\u00e7on mensuelle ou trimestrielle. Vous pouvez \u00e9galement leur proposer des contreparties exclusives en fonction du montant de leur soutien,&nbsp;ce qui vous permet d&rsquo;entretenir une relation privil\u00e9gi\u00e9e avec votre audience. Le crowdfunding (ou financement participatif) est un bon moyen d&rsquo;animer sa communaut\u00e9 et de cr\u00e9er du lien : de nombreux cr\u00e9ateurs et cr\u00e9atrices de contenus ont recours \u00e0 cette&nbsp;m\u00e9thode de financement, pourquoi pas vous ?&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Sceptique ?&nbsp;<\/em><\/p>\n\n\n<div class='eckosc eckosc_full_width_block'>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-14329 lazyload\" data-src=\"https:\/\/fr.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi.png\" alt=\"\" width=\"2004\" height=\"1076\" data-srcset=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi.png 2004w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-300x161.png 300w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-640x344.png 640w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-768x412.png 768w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-1536x825.png 1536w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-1920x1031.png 1920w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-1680x902.png 1680w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-1240x666.png 1240w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-860x462.png 860w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-680x365.png 680w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-500x268.png 500w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-400x215.png 400w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-200x107.png 200w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-50x27.png 50w\" data-sizes=\"(max-width: 2004px) 100vw, 2004px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 2004px; --smush-placeholder-aspect-ratio: 2004\/1076;\" \/><noscript><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-14329\" src=\"https:\/\/fr.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi.png\" alt=\"\" width=\"2004\" height=\"1076\" srcset=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi.png 2004w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-300x161.png 300w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-640x344.png 640w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-768x412.png 768w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-1536x825.png 1536w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-1920x1031.png 1920w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-1680x902.png 1680w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-1240x666.png 1240w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-860x462.png 860w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-680x365.png 680w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-500x268.png 500w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-400x215.png 400w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-200x107.png 200w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/08\/tsugi-50x27.png 50w\" sizes=\"(max-width: 2004px) 100vw, 2004px\" \/><\/noscript><\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\"><em>Tsugi Radio a r\u00e9colt\u00e9 + de 7000 \u20ac gr\u00e2ce au financement participatif. Pourquoi pas vous ?&nbsp;<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">Vous avez d&rsquo;autres id\u00e9es sur la fa\u00e7on de<strong> gagner de l&rsquo;argent gr\u00e2ce \u00e0 votre radio<\/strong> ? Nous attendons vos t\u00e9moignages dans les commentaires !<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/fr.radioking.com\/creer-radio\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" width=\"1240\" height=\"369\" data-src=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2021\/06\/yellow-fr.png\" alt=\"\" class=\"wp-image-26168 lazyload\" data-srcset=\"https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr.png?lossy=0&amp;strip=1&amp;webp=1 1240w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-300x89.png?lossy=0&amp;strip=1&amp;webp=1 300w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-640x190.png?lossy=0&amp;strip=1&amp;webp=1 640w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-768x229.png?lossy=0&amp;strip=1&amp;webp=1 768w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-860x256.png?lossy=0&amp;strip=1&amp;webp=1 860w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-680x202.png?lossy=0&amp;strip=1&amp;webp=1 680w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-500x149.png?lossy=0&amp;strip=1&amp;webp=1 500w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-400x119.png?lossy=0&amp;strip=1&amp;webp=1 400w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-200x60.png?lossy=0&amp;strip=1&amp;webp=1 200w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-50x15.png?lossy=0&amp;strip=1&amp;webp=1 50w\" data-sizes=\"(max-width: 1240px) 100vw, 1240px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1240px; --smush-placeholder-aspect-ratio: 1240\/369;\" \/><noscript><img decoding=\"async\" loading=\"lazy\" width=\"1240\" height=\"369\" src=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2021\/06\/yellow-fr.png\" alt=\"\" class=\"wp-image-26168\" srcset=\"https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr.png?lossy=0&amp;strip=1&amp;webp=1 1240w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-300x89.png?lossy=0&amp;strip=1&amp;webp=1 300w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-640x190.png?lossy=0&amp;strip=1&amp;webp=1 640w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-768x229.png?lossy=0&amp;strip=1&amp;webp=1 768w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-860x256.png?lossy=0&amp;strip=1&amp;webp=1 860w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-680x202.png?lossy=0&amp;strip=1&amp;webp=1 680w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-500x149.png?lossy=0&amp;strip=1&amp;webp=1 500w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-400x119.png?lossy=0&amp;strip=1&amp;webp=1 400w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-200x60.png?lossy=0&amp;strip=1&amp;webp=1 200w, https:\/\/b3213589.smushcdn.com\/3213589\/wp-content\/uploads\/2021\/06\/yellow-fr-50x15.png?lossy=0&amp;strip=1&amp;webp=1 50w\" sizes=\"(max-width: 1240px) 100vw, 1240px\" \/><\/noscript><\/a><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il existe diff\u00e9rents moyens de mon\u00e9tiser son projet radio.<\/p>\n","protected":false},"author":60,"featured_media":14207,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[588],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/posts\/14302"}],"collection":[{"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/comments?post=14302"}],"version-history":[{"count":25,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/posts\/14302\/revisions"}],"predecessor-version":[{"id":36279,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/posts\/14302\/revisions\/36279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/media\/14207"}],"wp:attachment":[{"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/media?parent=14302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/categories?post=14302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/tags?post=14302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}