{"id":11200,"date":"2017-03-17T14:27:29","date_gmt":"2017-03-17T13:27:29","guid":{"rendered":"https:\/\/www.radioking.com\/blog\/?p=11200"},"modified":"2025-11-26T16:56:19","modified_gmt":"2025-11-26T15:56:19","slug":"showcase-decouvrez-poptastic","status":"publish","type":"post","link":"https:\/\/fr.radioking.com\/blog\/showcase-decouvrez-poptastic\/","title":{"rendered":"Showcase: d\u00e9couvrez Poptastic"},"content":{"rendered":"<p>On vous propose aujourd&rsquo;hui de d\u00e9couvrir Poptastic !\u00a0<!--more--><\/p>\n<h3><b><\/b><span style=\"color: #953738;\"><strong>. Pouvez-vous nous d\u00e9crire votre projet et les origines de \u00abPoptastic Radio \u00bb en quelques mots?<\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>J&rsquo;\u00e9coute beaucoup la radio sur le Net, mais \u00e0 force de zapper entre plusieurs radios, je me suis dit qu&rsquo;il fallait passer le pas ! Et voil\u00e0, Poptastic Radio est n\u00e9e le 31 mai 2013 ! L&rsquo;id\u00e9e au d\u00e9part \u00e9tait de proposer <strong>un format Pop britannique essentiellement<\/strong>, <strong>en privil\u00e9giant la Britpop, l&rsquo;Indie, le Rock alternatif et les nouveaux talents<\/strong>. La programmation est compos\u00e9e de singles ET d&rsquo;extraits d&rsquo;albums, \u00e9galement d&rsquo;une s\u00e9lection de titres issus du classement des meilleures ventes en Angleterre et des sons l\u00e9gendaires qui ont marqu\u00e9 l&rsquo;histoire de la Pop Music.<\/p>\n<p>En 2017, la base de la programmation est inchang\u00e9e, nous avons juste inject\u00e9 quelques titres fran\u00e7ais et surtout nous allons faire de Poptastic Radio une radio fran\u00e7aise d\u00e9di\u00e9e aux fans de Londres et de l&rsquo;Angleterre, en termes de musique bien s\u00fbr mais pas seulement !<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<h3><span style=\"color: #953738;\"><strong>\u00a0. Aviez-vous une exp\u00e9rience dans l\u2019univers de la radio auparavant ?<\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>J&rsquo;ai commenc\u00e9 \u00e0 faire de la radio en 1981. D\u00e9j\u00e0 \u00e0 l&rsquo;\u00e9poque, j&rsquo;\u00e9tais tr\u00e8s int\u00e9ress\u00e9 par ce qui se passait en Angleterre, <strong>les radios ill\u00e9gales<\/strong> en ondes moyennes et ondes courtes, les radios offshores comme Radio Caroline. Et puis, il y a eu <strong>la lib\u00e9ralisation des ondes en 1981<\/strong>, et \u00e0 partir de l\u00e0 j&rsquo;ai commenc\u00e9 \u00e0 bosser au sein de radios associatives, puis priv\u00e9es, jusqu&rsquo;\u00e0 passer plus de 10 ans de ma vie entre NRJ et Nostalgie. J&rsquo;ai touch\u00e9 un peu \u00e0 tout, de l&rsquo;animation (fort heureusement pas trop longtemps) \u00e0 la production de pubs, en passant par la programmation musicale, la r\u00e9alisation, et m\u00eame la HF.<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span style=\"color: #ffffff;\"><br \/>\n<img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-11492 alignnone lazyload\" data-src=\"https:\/\/fr.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1.png\" alt=\"\" width=\"759\" height=\"450\" data-srcset=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1.png 759w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-300x178.png 300w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-640x379.png 640w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-680x403.png 680w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-500x296.png 500w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-400x237.png 400w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-200x119.png 200w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-50x30.png 50w\" data-sizes=\"(max-width: 759px) 100vw, 759px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 759px; --smush-placeholder-aspect-ratio: 759\/450;\" \/><noscript><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-11492 alignnone\" src=\"https:\/\/fr.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1.png\" alt=\"\" width=\"759\" height=\"450\" srcset=\"https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1.png 759w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-300x178.png 300w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-640x379.png 640w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-680x403.png 680w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-500x296.png 500w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-400x237.png 400w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-200x119.png 200w, https:\/\/www.radioking.com\/blog\/wp-content\/uploads\/2017\/03\/poptastic-1-50x30.png 50w\" sizes=\"(max-width: 759px) 100vw, 759px\" \/><\/noscript><\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<h3><span style=\"color: #953738;\"><strong><span class=\"im\">. Comment avez-vous connu RadioKing ?<\/span><\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>Nous sommes arriv\u00e9s sur RadioKing par Internet et le bouche-\u00e0-oreille. Nous \u00e9tions avant sur une autre plateforme dont nous n&rsquo;\u00e9tions pas satisfaits. D&rsquo;autres radios ayant test\u00e9 RadioKing avant nous, nous avaient vant\u00e9 les m\u00e9rites de cette plateforme 100% fran\u00e7aise et apr\u00e8s avoir test\u00e9 le produit, nous avons sign\u00e9 !<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<h3><span class=\"im\"><span style=\"color: #953738;\"><strong>. Selon vous, quelles sont les fonctionnalit\u00e9s indispensables propos\u00e9es par RadioKing \u00e0 une radio ?<\/strong><\/span><b><br \/>\n<\/b><\/span><\/h3>\n<h3><span style=\"color: #ffffff;\">.<\/span><\/h3>\n<p>J&rsquo;en vois plusieurs ! L&rsquo;ensemble du syst\u00e8me de programmation automatique est franchement bien vu, bien pens\u00e9. <strong>La gestion de la m\u00e9diath\u00e8que<\/strong> et la possibilit\u00e9 de r\u00e9gler les points de mix au cas par cas, \u00e7a c&rsquo;est tr\u00e8s important pour le rendu \u00e0 l&rsquo;antenne. Les diff\u00e9rentes qualit\u00e9s de flux offertes sont aussi importantes. Par exemple, pouvoir proposer du 48 Khz c&rsquo;est bien pour les pays o\u00f9 l&rsquo;ADSL est peu ou pas pr\u00e9sente, et chez nous c&rsquo;est un point fort pour l&rsquo;\u00e9coute sur les smartphones car plus \u00e9conomiques pour les forfaits !<strong> Les stats, outil indispensable<\/strong> pour savoir o\u00f9 l&rsquo;on en est,<strong> les widgets<\/strong> pour int\u00e9grer le player sur un site&#8230; Un mot aussi sur l&rsquo;application <strong>AirKing<\/strong> qui permet de faire du direct, tr\u00e8s facilement depuis son navigateur. Qui aurait pu imaginer un tel outil il y a encore quelque ann\u00e9es ?!<\/p>\n<h3><span style=\"color: #ffffff;\">.<\/span><\/h3>\n<h3><span style=\"color: #953738;\"><strong>. Quels sont les diff\u00e9rents moyens d\u2019\u00e9couter \u00ab\u00a0 Poptastic Radio\u00a0 \u00bb ?<\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>Outre le site de RadioKing et celui de<strong> <a href=\"http:\/\/www.poptastic-radio.com\/\" target=\"_blank\" rel=\"noopener\">Poptastic Radio<\/a><\/strong>, la radio est accessible sur l&rsquo;ensemble des principales plateformes d&rsquo;\u00e9coute mondiales telles que TuneIn, Radioline, Orange, \u00e0 la TV avec la Freebox, iTunes, mais \u00e9galement sur l&rsquo;application du site, disponible pour Android et iOS.<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><iframe loading=\"lazy\" id=\"idFrame\" data-src=\"https:\/\/www.radioking.com\/widgets\/player\/player.php?id=18893&amp;c=%231E7FCB&amp;ii=&amp;p=1&amp;pp=1&amp;i=1&amp;eq=1&amp;po=1&amp;t=1&amp;a=0&amp;f=big\" name=\"idFrame\" width=\"445\" height=\"196\" frameborder=\"0\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<h3><span style=\"color: #953738;\"><strong>. Pouvez-vous nous parler du profil de vos auditeurs ?<\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>Difficile d&rsquo;\u00e9tablir une carte d&rsquo;identit\u00e9 de l&rsquo;auditeur (trice) type, mais je dirai que, d&rsquo;apr\u00e8s les retours que nous avons, la tranche d&rsquo;\u00e2ge moyenne se situe <strong>entre 25 et 55 ans<\/strong>&#8230; La grande majorit\u00e9 de l&rsquo;audience se situe en France, puis viennent les \u00c9tats-Unis, l&rsquo;Allemagne, l&rsquo;Espagne, l&rsquo;Irlande et la Grande-Bretagne. Ce sont <strong>des personnes qui souhaitent avant tout \u00e9couter de la Pop anglaise<\/strong>, pas r\u00e9calcitrants \u00e0 l&rsquo;\u00e9coute de hits, mais dont ce n&rsquo;est certainement pas la recherche primordiale !<\/p>\n<h3><span style=\"color: #ffffff;\"><b>.<\/b><\/span><\/h3>\n<h3><span style=\"color: #953738;\"><strong>. Qu\u2019est-ce que vous appr\u00e9ciez le plus dans ce projet ?<\/strong><\/span><\/h3>\n<h3><span style=\"color: #ffffff;\">.<\/span><\/h3>\n<p>En premier, il y a le plaisir de partager nos bonnes vibrations avec celles et ceux qui nous \u00e9coutent. La radio permet de faire <strong>d\u00e9couvrir des artistes, des nouveaux titres<\/strong>, sans oublier de ressortir des titres l\u00e9gendaires.<br \/>\nNous sommes constamment amen\u00e9s \u00e0 \u00e9couter et \u00e0 s\u00e9lectionner de nouveaux artistes, \u00e7a aussi c&rsquo;est tr\u00e8s excitant !<br \/>\nEnsuite, la dynamique ! Faire vivre une radio Internet, quelle que soit sa taille, demande une attention quotidienne : faire \u00e9voluer la programmation musicale, trouver de nouvelles id\u00e9es, comprendre ce qui fonctionne ou pas, surveiller ce qui passe \u00e0 l&rsquo;antenne&#8230; Sinc\u00e8rement, \u00e0 l&rsquo;heure des plateformes de streaming o\u00f9 les titres s&rsquo;encha\u00eenent de mani\u00e8re fantomatique, <strong>c&rsquo;est extr\u00eamement stimulant de constater que la demande pour les radios \u00ab\u00a0traditionnelles\u00a0\u00bb<\/strong> (avec des vrais programmateurs, des jingles, des sessions \u00e0 th\u00e8mes) est toujours aussi forte, voire grandissante.<\/p>\n<h3><span style=\"color: #ffffff;\">.<\/span><\/h3>\n<h3><span class=\"im\"><span style=\"color: #953738;\"><strong>. Comment s\u00e9lectionnez-vous les artistes diffus\u00e9s sur \u00ab\u00a0\u00a0 Poptastic Radio\u00a0 \u00bb ?<\/strong><\/span><br \/>\n<\/span><\/h3>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>L&rsquo;id\u00e9e de d\u00e9part est de ne pas reproduire ce qui existe ailleurs, notamment sur les grands r\u00e9seaux nationaux. Pour autant, pas question de faire une radio \u00e9litiste !\u00a0 La plupart des artistes que nous passons sont issus de la sc\u00e8ne Pop UK, et <strong>on tente de rester le plus possible \u00e9clectiques<\/strong> dans nos choix. Et l&rsquo;antenne est ouverte aux nouveaux talents, comme je l&rsquo;ai dit. Aujourd&rsquo;hui, ces artistes peuvent b\u00e9n\u00e9ficier d&rsquo;une exposition comme jamais, gr\u00e2ce aux dizaines de milliers de radios qui existent sur la plan\u00e8te, et nous sommes fiers d&rsquo;en faire partie ! D&rsquo;autant que pour beaucoup d&rsquo;entre-eux, les productions propos\u00e9es sont r\u00e9ellement de tr\u00e8s bonne qualit\u00e9. On se demande m\u00eame comment tant d&rsquo;autres radios passent \u00e0 c\u00f4t\u00e9 d&rsquo;artistes aussi talentueux !<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<div class=\"rk_widget_artists_broadcast\" data-idradio=\"18893\" data-nbartists=\"12\"><\/div>\n<p><script type=\"text\/javascript\" src=\"https:\/\/www.radioking.com\/widgets\/artists-broadcast\/script.min.js\"><\/script><\/p>\n<h3><b><span style=\"color: #ffffff;\">.<\/span><\/b><\/h3>\n<h3><span style=\"color: #953738;\"><strong>. Avez-vous une anecdote sympathique qui s\u2019est d\u00e9roul\u00e9e en rapport avec votre radio ou la mise en place de ce projet ?<\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>Oui ! Juste avant le lancement du projet, un \u00e9v\u00e9nement a probablement eu un impact d\u00e9terminant sur la naissance de Poptastic Radio : lors d&rsquo;un voyage \u00e0 Londres, ma compagne et moi-m\u00eame avons eu l&rsquo;extraordinaire chance, dans des circonstances que je ne peux raconter ici, de visiter <strong>le bateau-radio de Radio Caroline, le \u00ab\u00a0Ross Revenge\u00a0\u00bb<\/strong>, les studios, les \u00e9metteurs&#8230; absolument tout ! Radio Caroline est cette radio n\u00e9e dans les ann\u00e9es 60 qui diffusait, depuis les eaux internationales en mer du Nord, une programmation Pop quasiment inexistante sur les ondes de la BBC \u00e0 l&rsquo;\u00e9poque. Le \u00ab\u00a0Ross\u00a0\u00bb est un navire mythique car il a \u00e9t\u00e9 le th\u00e9\u00e2tre des derni\u00e8res ann\u00e9es de Caroline en mer, jusqu&rsquo;\u00e0 l&rsquo;arr\u00eat total par les autorit\u00e9s anglaises au d\u00e9but des ann\u00e9es 90. Aujourd&rsquo;hui, la radio continue d&rsquo;\u00e9mettre depuis des studios \u00e0 terre et r\u00e9guli\u00e8rement depuis le Ross Revenge ancr\u00e9 au large de l&rsquo;Angleterre, \u00e0 l&rsquo;occasion d&rsquo;\u00e9v\u00e9nements.<\/p>\n<h3><span style=\"color: #ffffff;\">.<\/span><\/h3>\n<h3><span style=\"color: #953738;\"><strong>. Quels sont les prochains projets pour \u00ab\u00a0 Poptastic Radio \u00bb ?<\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>Cette ann\u00e9e 2017 est importante car nous avons d\u00e9cid\u00e9 de nous consacrer principalement \u00e0 nos auditeurs en France. <strong>Nous lan\u00e7ons actuellement la version en fran\u00e7ais de notre site Internet<\/strong>. Celui-ci proposera l&rsquo;actualit\u00e9 de Poptastic Radio (titres diffus\u00e9s, nouveaut\u00e9s, \u00e9missions) ainsi que des infos pour tous les fans de Londres et l&rsquo;actu de la sc\u00e8ne Pop anglaise, toujours tr\u00e8s riche puisque Londres reste tout de m\u00eame LE sanctuaire de la Pop. Parall\u00e8lement, <strong>nous travaillons sur un nouvel habillage incluant \u00e9galement des jingles en fran\u00e7ais<\/strong>.<\/p>\n<p>A ce titre, je me permets de pr\u00e9ciser que nous recherchons toujours des collaborateurs (trices) b\u00e9n\u00e9voles pour \u00e9crire des articles en fran\u00e7ais sur l&rsquo;actu musicale en Angleterre et \u00e0 Londres. C&rsquo;est, je pense, un terrain de jeu id\u00e9al pour celles et ceux qui souhaitent tester leur talents de r\u00e9dacteur.<\/p>\n<h3><span style=\"color: #ffffff;\"><b>.<\/b><\/span><\/h3>\n<h3><span style=\"color: #953738;\"><strong>. Pour finir, un petit mot pour ceux qui souhaitent se lancer dans l\u2019aventure ?<\/strong><\/span><\/h3>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>Cr\u00e9er une radio sur Internet est une vraie aventure, qui n\u00e9cessite un vrai projet, <strong>du temps et de la passion<\/strong>. Si ces crit\u00e8res sont r\u00e9unis, il reste, pour concr\u00e9tiser un tel projet, <strong>l&rsquo;outil indispensable, fiable et efficace<\/strong>, et je peux vous dire, pour avoir \u00e9tudi\u00e9 le dossier et test\u00e9 d&rsquo;autres plateformes, que RadioKing est LA solution. Hormis les fonctionnalit\u00e9s \u00e9voqu\u00e9es tout \u00e0 l&rsquo;heure, il faut souligner <strong>l&rsquo;efficacit\u00e9 de l&rsquo;\u00e9quipe technique<\/strong>, un point crucial pour le bon fonctionnement d&rsquo;une radio bas\u00e9e sur Internet.<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<div class=\"gmail_extra\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>On vous propose aujourd&rsquo;hui de d\u00e9couvrir Poptastic !\u00a0<\/p>\n","protected":false},"author":59,"featured_media":13886,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/posts\/11200"}],"collection":[{"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/comments?post=11200"}],"version-history":[{"count":30,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/posts\/11200\/revisions"}],"predecessor-version":[{"id":13887,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/posts\/11200\/revisions\/13887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/media\/13886"}],"wp:attachment":[{"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/media?parent=11200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/categories?post=11200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioking.com\/blog\/wp-json\/wp\/v2\/tags?post=11200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}